{
    "id": 50979,
    "date": "2022-10-17T15:23:15",
    "date_gmt": "2022-10-17T13:23:15",
    "guid": {
        "rendered": "https:\/\/alfadescompte.ad\/?product=g-data-total-security-4-postes-abonnement-3-ans"
    },
    "modified": "2026-03-04T15:28:33",
    "modified_gmt": "2026-03-04T14:28:33",
    "slug": "g-data-total-security-4-postes-abonnement-3-ans",
    "status": "publish",
    "type": "product",
    "link": "https:\/\/alfadescompte.ad\/fr\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/",
    "title": {
        "rendered": "G DATA Total Security 2026 &#8211; 4 postes &#8211; Abonnement 3 ans"
    },
    "content": {
        "rendered": "<p>G DATA Total Security offrira une protection efficace contre les virus, les chevaux de Troie, les attaques pirates et toutes autres menaces. Il vous permettra \u00e9galement de contr\u00f4ler l&rsquo;acc\u00e8s \u00e0 vos donn\u00e9es. Retrouvez une protection anti-exploits tr\u00e8s efficace contre l&rsquo;exploitation des failles de s\u00e9curit\u00e9, par les logiciels malveillants.<\/p>\n<h2>UNE S\u00c9CURIT\u00c9 TOTALE POUR VOTRE MACHINE<\/h2>\n<p>G DATA Total Security propose de nombreuses fonctionnalit\u00e9s offrant une protection compl\u00e8te contre l&rsquo;ensemble des menaces.<\/p>\n<h3>UNE PROTECTION EFFICACE CONTRE LES DIFF\u00c9RENTS VIRUS<\/h3>\n<p>Les diff\u00e9rentes technologies associ\u00e9es, utilis\u00e9es par G DATA Total Security offrent un des meilleurs taux de d\u00e9tection contre les virus (anciens ou r\u00e9cents).<\/p>\n<h3>UNE PROTECTION CONTRE LES DANGERS INCONNUS<\/h3>\n<p>G DATA Total Security effectue une v\u00e9rification comportementale des fichiers. La reconnaissance proactive, associ\u00e9e \u00e0 l&rsquo;analyse en Cloud permettront au logiciel de s&rsquo;actualiser et de rester efficace face aux nouvelles menaces.<\/p>\n<h3>PROTECTION DE VOS MESSAGERIES<\/h3>\n<p>D\u00e8s la r\u00e9ception de vos messages, les contenus seront automatiquement analys\u00e9s afin de d\u00e9tecter les fichiers repr\u00e9sentant une menace.<\/p>\n<h3>LA PROTECTION ANTI-EXPLOITS<\/h3>\n<p>La protection Anti-exploit garantit une protection contre les failles des programmes install\u00e9s (plugin de navigateur, traitement de texte). Les programmes seront ainsi s\u00e9curis\u00e9s, ce qui \u00e9vitera l&rsquo;exploitation d&rsquo;\u00e9ventuelles failles.<\/p>\n<h3>VOS OP\u00c9RATIONS BANCAIRES ET ACHATS EN LIGNE EN TOUTE S\u00c9CURIT\u00c9<\/h3>\n<p>La technologie BankGuard brevet\u00e9e s\u00e9curisera vos donn\u00e9es et vous prot\u00e9gera des enregistreurs de frappe.<\/p>\n<h3>UN PARE-FEU PUISSANT CONTRE LES ATTAQUES PIRATES<\/h3>\n<p>Le pare-feu de G DATA Total Security, contr\u00f4lera toutes les connexions (entrantes ou sortantes), pour emp\u00eacher les attaques pirates et les attaques r\u00e9seau.<\/p>\n<h3>PROTECTION ANTISPAM<\/h3>\n<p>La protection antispam d\u00e9tectera et bloquera automatiquement les courriers ind\u00e9sirables et le hame\u00e7onnage.<\/p>\n<h3>PROT\u00c9GEZ VOS ENFANTS<\/h3>\n<p>Le contr\u00f4le parental vous permettra de surveiller la navigation de vos enfants, pour les prot\u00e9ger des contenus inappropri\u00e9s. En plus d&#8217;emp\u00eacher l&rsquo;acc\u00e8s aux sites dangereux, vous pourrez aussi d\u00e9terminer leur temps de navigation sur Internet ou le temps d&rsquo;utilisation de l&rsquo;ordinateur.<\/p>\n<h3>SAUVEGARDES S\u00c9CURIS\u00c9ES DU SYST\u00c8ME<\/h3>\n<p>Le logiciel vous permettra de r\u00e9aliser des sauvegardes s\u00e9curis\u00e9es de votre syst\u00e8me, qu&rsquo;il sera possible de stocker dans les diff\u00e9rents services Cloud (Dropbox et Google Drive). Ces sauvegardes seront automatis\u00e9es.<\/p>\n<h3>CONTR\u00d4LEZ L&rsquo;ACC\u00c8S AUX DIFF\u00c9RENTS SUPPORTS ET P\u00c9RIPH\u00c9RIQUES<\/h3>\n<p>G DATA Total Security vous permettra de contr\u00f4ler et limiter les acc\u00e8s \u00e0 vos diff\u00e9rents supports et p\u00e9riph\u00e9riques, quels qu&rsquo;ils soient (Carte m\u00e9moire, cl\u00e9s USB, etc.).<\/p>\n<h3>PROT\u00c9GEZ VOS DONN\u00c9ES CONFIDENTIELLES<\/h3>\n<p>L&rsquo;utilisation du coffre-fort chiffr\u00e9, emp\u00eachera les acc\u00e8s \u00e0 vos donn\u00e9es confidentielles (fichiers, informations), si vous ne l&rsquo;avez pas autoris\u00e9.<\/p>\n<h3>PASSWORT MANAGER<\/h3>\n<p>Cette fonction m\u00e9morise les mots de passe que vous utilisez dans des boutiques en ligne, des forums, votre messagerie \u00e9lectronique, etc. Vous pouvez facilement int\u00e9grer notre gestionnaire de mots de passe \u00e0 votre navigateur. Les mots de passe et les coordonn\u00e9es sont ainsi automatiquement renseign\u00e9s quand vous le souhaitez.<\/p>\n<p>BackupProt\u00e9gez vos donn\u00e9es automatiquement, sur votre PC ou dans le Cloud. Gr\u00e2ce aux sauvegardes prot\u00e9g\u00e9es par un mot de passe, vos donn\u00e9es sont s\u00e9curis\u00e9es en permanence. Utilisez Google Drive ou Dropbox pour mettre vos donn\u00e9es en s\u00e9curit\u00e9.<\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<ul>\n<li class=\"point-fort\">Editeur europ\u00e9en, donn\u00e9es stock\u00e9es en Europe<\/li>\n<li class=\"point-fort\">Produit certifi\u00e9 par AV-Test.org<\/li>\n<li class=\"point-fort\">Suite de s\u00e9curit\u00e9 tout-en-un<\/li>\n<li class=\"point-fort\">Int\u00e8gre aussi le contr\u00f4le parental<\/li>\n<li class=\"point-fort\">Sauvegarde et gestionnaire de mots de passe<\/li>\n<li class=\"point-fort\">Technologie IA contre les nouvelles menaces<\/li>\n<li class=\"point-fort\">Couvre vos PC, Mac, tablettes et smartphone<\/li>\n<li class=\"point-fort\">Assistance t\u00e9l\u00e9phonique gratuite en fran\u00e7ais<\/li>\n<\/ul>\n<p>Acheter et T\u00e9l\u00e9charger <strong>G DATA Total Security<\/strong><\/p>\n<p>Apr\u00e8s avoir pass\u00e9 votre commande, vous recevrez :<\/p>\n<ul>\n<li>Le code de la cl\u00e9 d\u2019activation de <strong>G DATA Total Security<\/strong><\/li>\n<li>Le lien de t\u00e9l\u00e9chargement pour <strong>G DATA Total Security<\/strong><\/li>\n<li>Les guides d\u2019installation et d\u2019activation<\/li>\n<\/ul>\n<p>Notre service client\u00e8le est disponible 7\/7 jours<\/p>",
        "protected": false
    },
    "featured_media": 55822,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "meta": [],
    "product_brand": [],
    "product_cat": [
        1437,
        1501,
        20
    ],
    "product_tag": [],
    "class_list": {
        "0": "post-50979",
        "1": "product",
        "2": "type-product",
        "3": "status-publish",
        "4": "has-post-thumbnail",
        "6": "product_cat-g-data",
        "7": "product_cat-total-security-g-data",
        "8": "product_cat-securite",
        "10": "first",
        "11": "instock",
        "12": "sale",
        "13": "downloadable",
        "14": "virtual",
        "15": "purchasable",
        "16": "product-type-simple",
        "17": "czr-hentry"
    },
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G DATA Total Security 2026 - 4 postes - Abonnement 3 ans - Alfa Descompte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alfadescompte.ad\/fr\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G DATA Total Security 2026 - 4 postes - Abonnement 3 ans - Alfa Descompte\" \/>\n<meta property=\"og:description\" content=\"Editeur europ\u00e9en, donn\u00e9es stock\u00e9es en Europe  Produit certifi\u00e9 par AV-Test.org  Suite de s\u00e9curit\u00e9 tout-en-un  Int\u00e8gre aussi le contr\u00f4le parental  Sauvegarde et gestionnaire de mots de passe  Technologie IA contre les nouvelles menaces  Couvre vos PC, Mac, tablettes et smartphone  Assistance t\u00e9l\u00e9phonique gratuite en fran\u00e7ais  Acheter et T\u00e9l\u00e9charger G DATA Total Security  Apr\u00e8s avoir pass\u00e9 votre commande, vous recevrez :   Le code de la cl\u00e9 d\u2019activation de G DATA Total Security  Le lien de t\u00e9l\u00e9chargement pour G DATA Total Security  Les guides d\u2019installation et d\u2019activation  Notre service client\u00e8le est disponible 7\/7 jours\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alfadescompte.ad\/fr\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"Alfa Descompte\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-04T14:28:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alfadescompte.ad\/wp-content\/uploads\/2022\/10\/ChatGPT-Image-4-mars-2026-13_58_40.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/produit\\\/g-data-total-security-4-postes-abonnement-3-ans\\\/\",\"url\":\"https:\\\/\\\/alfadescompte.ad\\\/produit\\\/g-data-total-security-4-postes-abonnement-3-ans\\\/\",\"name\":\"G DATA Total Security 2026 - 4 postes - Abonnement 3 ans - Alfa Descompte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/produit\\\/g-data-total-security-4-postes-abonnement-3-ans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/produit\\\/g-data-total-security-4-postes-abonnement-3-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alfadescompte.ad\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ChatGPT-Image-4-mars-2026-13_58_40.png\",\"datePublished\":\"2022-10-17T13:23:15+00:00\",\"dateModified\":\"2026-03-04T14:28:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/produit\\\/g-data-total-security-4-postes-abonnement-3-ans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alfadescompte.ad\\\/produit\\\/g-data-total-security-4-postes-abonnement-3-ans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/produit\\\/g-data-total-security-4-postes-abonnement-3-ans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alfadescompte.ad\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ChatGPT-Image-4-mars-2026-13_58_40.png\",\"contentUrl\":\"https:\\\/\\\/alfadescompte.ad\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ChatGPT-Image-4-mars-2026-13_58_40.png\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/produit\\\/g-data-total-security-4-postes-abonnement-3-ans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/alfadescompte.ad\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/alfadescompte.ad\\\/en\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"G DATA Total Security 2026 &#8211; 4 postes &#8211; Abonnement 3 ans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/#website\",\"url\":\"https:\\\/\\\/alfadescompte.ad\\\/\",\"name\":\"Alfa Descompte\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alfadescompte.ad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/#organization\",\"name\":\"Alfa Descompte\",\"url\":\"https:\\\/\\\/alfadescompte.ad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alfadescompte.ad\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-logo-alfa-1-1.png\",\"contentUrl\":\"https:\\\/\\\/alfadescompte.ad\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-logo-alfa-1-1.png\",\"width\":424,\"height\":128,\"caption\":\"Alfa Descompte\"},\"image\":{\"@id\":\"https:\\\/\\\/alfadescompte.ad\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "G DATA Total Security 2026 - 4 postes - Abonnement 3 ans - Alfa Descompte",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "https:\/\/alfadescompte.ad\/fr\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/",
        "og_locale": "fr_FR",
        "og_type": "article",
        "og_title": "G DATA Total Security 2026 - 4 postes - Abonnement 3 ans - Alfa Descompte",
        "og_description": "Editeur europ\u00e9en, donn\u00e9es stock\u00e9es en Europe  Produit certifi\u00e9 par AV-Test.org  Suite de s\u00e9curit\u00e9 tout-en-un  Int\u00e8gre aussi le contr\u00f4le parental  Sauvegarde et gestionnaire de mots de passe  Technologie IA contre les nouvelles menaces  Couvre vos PC, Mac, tablettes et smartphone  Assistance t\u00e9l\u00e9phonique gratuite en fran\u00e7ais  Acheter et T\u00e9l\u00e9charger G DATA Total Security  Apr\u00e8s avoir pass\u00e9 votre commande, vous recevrez :   Le code de la cl\u00e9 d\u2019activation de G DATA Total Security  Le lien de t\u00e9l\u00e9chargement pour G DATA Total Security  Les guides d\u2019installation et d\u2019activation  Notre service client\u00e8le est disponible 7\/7 jours",
        "og_url": "https:\/\/alfadescompte.ad\/fr\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/",
        "og_site_name": "Alfa Descompte",
        "article_modified_time": "2026-03-04T14:28:33+00:00",
        "og_image": [
            {
                "width": 1024,
                "height": 1024,
                "url": "https:\/\/alfadescompte.ad\/wp-content\/uploads\/2022\/10\/ChatGPT-Image-4-mars-2026-13_58_40.png",
                "type": "image\/png"
            }
        ],
        "twitter_card": "summary_large_image",
        "twitter_misc": {
            "Dur\u00e9e de lecture estim\u00e9e": "3 minutes"
        },
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/alfadescompte.ad\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/",
                    "url": "https:\/\/alfadescompte.ad\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/",
                    "name": "G DATA Total Security 2026 - 4 postes - Abonnement 3 ans - Alfa Descompte",
                    "isPartOf": {
                        "@id": "https:\/\/alfadescompte.ad\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "https:\/\/alfadescompte.ad\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/#primaryimage"
                    },
                    "image": {
                        "@id": "https:\/\/alfadescompte.ad\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/alfadescompte.ad\/wp-content\/uploads\/2022\/10\/ChatGPT-Image-4-mars-2026-13_58_40.png",
                    "datePublished": "2022-10-17T13:23:15+00:00",
                    "dateModified": "2026-03-04T14:28:33+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/alfadescompte.ad\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/#breadcrumb"
                    },
                    "inLanguage": "fr-FR",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/alfadescompte.ad\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "fr-FR",
                    "@id": "https:\/\/alfadescompte.ad\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/#primaryimage",
                    "url": "https:\/\/alfadescompte.ad\/wp-content\/uploads\/2022\/10\/ChatGPT-Image-4-mars-2026-13_58_40.png",
                    "contentUrl": "https:\/\/alfadescompte.ad\/wp-content\/uploads\/2022\/10\/ChatGPT-Image-4-mars-2026-13_58_40.png",
                    "width": 1024,
                    "height": 1024
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/alfadescompte.ad\/produit\/g-data-total-security-4-postes-abonnement-3-ans\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Accueil",
                            "item": "https:\/\/alfadescompte.ad\/fr\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Boutique",
                            "item": "https:\/\/alfadescompte.ad\/en\/boutique\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 3,
                            "name": "G DATA Total Security 2026 &#8211; 4 postes &#8211; Abonnement 3 ans"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/alfadescompte.ad\/#website",
                    "url": "https:\/\/alfadescompte.ad\/",
                    "name": "Alfa Descompte",
                    "description": "",
                    "publisher": {
                        "@id": "https:\/\/alfadescompte.ad\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/alfadescompte.ad\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "fr-FR"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/alfadescompte.ad\/#organization",
                    "name": "Alfa Descompte",
                    "url": "https:\/\/alfadescompte.ad\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "fr-FR",
                        "@id": "https:\/\/alfadescompte.ad\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/alfadescompte.ad\/wp-content\/uploads\/2022\/04\/cropped-logo-alfa-1-1.png",
                        "contentUrl": "https:\/\/alfadescompte.ad\/wp-content\/uploads\/2022\/04\/cropped-logo-alfa-1-1.png",
                        "width": 424,
                        "height": 128,
                        "caption": "Alfa Descompte"
                    },
                    "image": {
                        "@id": "https:\/\/alfadescompte.ad\/#\/schema\/logo\/image\/"
                    }
                }
            ]
        }
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/alfadescompte.ad\/fr\/wp-json\/wp\/v2\/product\/50979",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/alfadescompte.ad\/fr\/wp-json\/wp\/v2\/product"
            }
        ],
        "about": [
            {
                "href": "https:\/\/alfadescompte.ad\/fr\/wp-json\/wp\/v2\/types\/product"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/alfadescompte.ad\/fr\/wp-json\/wp\/v2\/comments?post=50979"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/alfadescompte.ad\/fr\/wp-json\/wp\/v2\/media\/55822"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/alfadescompte.ad\/fr\/wp-json\/wp\/v2\/media?parent=50979"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "product_brand",
                "embeddable": true,
                "href": "https:\/\/alfadescompte.ad\/fr\/wp-json\/wp\/v2\/product_brand?post=50979"
            },
            {
                "taxonomy": "product_cat",
                "embeddable": true,
                "href": "https:\/\/alfadescompte.ad\/fr\/wp-json\/wp\/v2\/product_cat?post=50979"
            },
            {
                "taxonomy": "product_tag",
                "embeddable": true,
                "href": "https:\/\/alfadescompte.ad\/fr\/wp-json\/wp\/v2\/product_tag?post=50979"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}